{"id":59969,"date":"2026-01-22T01:10:46","date_gmt":"2026-01-21T18:10:46","guid":{"rendered":"https:\/\/accordhenryschein.test.phranakornsoft.com\/product\/excavator-exc127-128\/"},"modified":"2026-09-01T22:00:26","modified_gmt":"2026-09-01T15:00:26","slug":"excavator-exc127-128","status":"publish","type":"product","link":"https:\/\/accordhenryschein.com\/en\/product\/excavator-exc127-128\/","title":{"rendered":"EXCAVATOR # EXC127\/128"},"content":{"rendered":"<p>Excavators for removal of carious dentin.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Excavators for removal of carious dentin.<\/p>\n","protected":false},"featured_media":10357,"comment_status":"closed","ping_status":"open","template":"","meta":[],"product_brand":[2692],"product_cat":[1549,2296],"product_tag":[],"class_list":{"0":"post-59969","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-hu-friedy","7":"product_cat-hand-instruments","8":"product_cat-hioperativeandrestorative","10":"first","11":"instock","12":"purchasable","13":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/accordhenryschein.com\/en\/wp-json\/wp\/v2\/product\/59969","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/accordhenryschein.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/accordhenryschein.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/accordhenryschein.com\/en\/wp-json\/wp\/v2\/comments?post=59969"}],"version-history":[{"count":1,"href":"https:\/\/accordhenryschein.com\/en\/wp-json\/wp\/v2\/product\/59969\/revisions"}],"predecessor-version":[{"id":59970,"href":"https:\/\/accordhenryschein.com\/en\/wp-json\/wp\/v2\/product\/59969\/revisions\/59970"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/accordhenryschein.com\/en\/wp-json\/wp\/v2\/media\/10357"}],"wp:attachment":[{"href":"https:\/\/accordhenryschein.com\/en\/wp-json\/wp\/v2\/media?parent=59969"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/accordhenryschein.com\/en\/wp-json\/wp\/v2\/product_brand?post=59969"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/accordhenryschein.com\/en\/wp-json\/wp\/v2\/product_cat?post=59969"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/accordhenryschein.com\/en\/wp-json\/wp\/v2\/product_tag?post=59969"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}