{"id":57723,"date":"2026-01-22T00:43:35","date_gmt":"2026-01-21T17:43:35","guid":{"rendered":"https:\/\/accordhenryschein.test.phranakornsoft.com\/product\/ems-%e0%b8%ab%e0%b8%b1%e0%b8%a7%e0%b8%82%e0%b8%b9%e0%b8%94%e0%b8%ab%e0%b8%b4%e0%b8%99%e0%b8%9b%e0%b8%b9%e0%b8%99-tip-p-w-combitorque-ds011a\/"},"modified":"2026-09-01T21:25:43","modified_gmt":"2026-09-01T14:25:43","slug":"ems-%e0%b8%ab%e0%b8%b1%e0%b8%a7%e0%b8%82%e0%b8%b9%e0%b8%94%e0%b8%ab%e0%b8%b4%e0%b8%99%e0%b8%9b%e0%b8%b9%e0%b8%99-tip-p-w-combitorque-ds011a","status":"publish","type":"product","link":"https:\/\/accordhenryschein.com\/en\/product\/ems-%e0%b8%ab%e0%b8%b1%e0%b8%a7%e0%b8%82%e0%b8%b9%e0%b8%94%e0%b8%ab%e0%b8%b4%e0%b8%99%e0%b8%9b%e0%b8%b9%e0%b8%99-tip-p-w-combitorque-ds011a\/","title":{"rendered":"EMS \u0e2b\u0e31\u0e27\u0e02\u0e39\u0e14\u0e2b\u0e34\u0e19\u0e1b\u0e39\u0e19 TIP P W\/COMBITORQUE #DS011A"},"content":{"rendered":"<p>EMS Tip P Scaling Periodontal  For the removal of supragingival &#038; subgingival deposits in all quadrants.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>EMS Tip P Scaling Periodontal For the removal of supragingival &#038; subgingival deposits in all quadrants.<\/p>\n","protected":false},"featured_media":5258,"comment_status":"closed","ping_status":"open","template":"","meta":[],"product_brand":[637],"product_cat":[2287,2301],"product_tag":[],"class_list":{"0":"post-57723","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-ems","7":"product_cat-scalers-and-air-abrasion-units","8":"product_cat-scaling-tips","10":"first","11":"instock","12":"purchasable","13":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/accordhenryschein.com\/en\/wp-json\/wp\/v2\/product\/57723","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/accordhenryschein.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/accordhenryschein.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/accordhenryschein.com\/en\/wp-json\/wp\/v2\/comments?post=57723"}],"version-history":[{"count":1,"href":"https:\/\/accordhenryschein.com\/en\/wp-json\/wp\/v2\/product\/57723\/revisions"}],"predecessor-version":[{"id":57724,"href":"https:\/\/accordhenryschein.com\/en\/wp-json\/wp\/v2\/product\/57723\/revisions\/57724"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/accordhenryschein.com\/en\/wp-json\/wp\/v2\/media\/5258"}],"wp:attachment":[{"href":"https:\/\/accordhenryschein.com\/en\/wp-json\/wp\/v2\/media?parent=57723"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/accordhenryschein.com\/en\/wp-json\/wp\/v2\/product_brand?post=57723"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/accordhenryschein.com\/en\/wp-json\/wp\/v2\/product_cat?post=57723"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/accordhenryschein.com\/en\/wp-json\/wp\/v2\/product_tag?post=57723"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}